{"id":110,"count":11,"description":"","link":"https:\/\/cpi-europe.upv.es\/en\/tag\/cluster-2\/","name":"cluster 2","slug":"cluster-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>cluster 2 archivos | CPI EUROPE<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cluster 2 archivos | CPI EUROPE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpi-europe.upv.es\/en\/tag\/cluster-2\/\" \/>\n<meta property=\"og:site_name\" content=\"CPI EUROPE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UPV\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/cpi-europe.upv.es\/tag\/cluster-2\/\",\"url\":\"https:\/\/cpi-europe.upv.es\/tag\/cluster-2\/\",\"name\":\"cluster 2 archivos | CPI EUROPE\",\"isPartOf\":{\"@id\":\"https:\/\/cpi-europe.upv.es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/cpi-europe.upv.es\/tag\/cluster-2\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cpi-europe.upv.es\/tag\/cluster-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cpi-europe.upv.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cluster 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cpi-europe.upv.es\/#website\",\"url\":\"https:\/\/cpi-europe.upv.es\/\",\"name\":\"CPI EUROPE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cpi-europe.upv.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cpi-europe.upv.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cpi-europe.upv.es\/#organization\",\"name\":\"CPI Europe\",\"url\":\"https:\/\/cpi-europe.upv.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cpi-europe.upv.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cpi-europe.upv.es\/wp-content\/uploads\/2020\/12\/logo-cpi-web-ok.png\",\"contentUrl\":\"https:\/\/cpi-europe.upv.es\/wp-content\/uploads\/2020\/12\/logo-cpi-web-ok.png\",\"width\":869,\"height\":111,\"caption\":\"CPI Europe\"},\"image\":{\"@id\":\"https:\/\/cpi-europe.upv.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/UPV\",\"https:\/\/x.com\/UPV\",\"https:\/\/www.instagram.com\/instaUPV\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cluster 2 archivos | CPI EUROPE","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"cluster 2 archivos | CPI EUROPE","og_url":"https:\/\/cpi-europe.upv.es\/en\/tag\/cluster-2\/","og_site_name":"CPI EUROPE","twitter_card":"summary_large_image","twitter_site":"@UPV","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cpi-europe.upv.es\/tag\/cluster-2\/","url":"https:\/\/cpi-europe.upv.es\/tag\/cluster-2\/","name":"cluster 2 archivos | CPI EUROPE","isPartOf":{"@id":"https:\/\/cpi-europe.upv.es\/#website"},"breadcrumb":{"@id":"https:\/\/cpi-europe.upv.es\/tag\/cluster-2\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/cpi-europe.upv.es\/tag\/cluster-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cpi-europe.upv.es\/"},{"@type":"ListItem","position":2,"name":"cluster 2"}]},{"@type":"WebSite","@id":"https:\/\/cpi-europe.upv.es\/#website","url":"https:\/\/cpi-europe.upv.es\/","name":"CPI EUROPE","description":"","publisher":{"@id":"https:\/\/cpi-europe.upv.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpi-europe.upv.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cpi-europe.upv.es\/#organization","name":"CPI Europe","url":"https:\/\/cpi-europe.upv.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cpi-europe.upv.es\/#\/schema\/logo\/image\/","url":"https:\/\/cpi-europe.upv.es\/wp-content\/uploads\/2020\/12\/logo-cpi-web-ok.png","contentUrl":"https:\/\/cpi-europe.upv.es\/wp-content\/uploads\/2020\/12\/logo-cpi-web-ok.png","width":869,"height":111,"caption":"CPI Europe"},"image":{"@id":"https:\/\/cpi-europe.upv.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UPV","https:\/\/x.com\/UPV","https:\/\/www.instagram.com\/instaUPV\/"]}]}},"_links":{"self":[{"href":"https:\/\/cpi-europe.upv.es\/en\/wp-json\/wp\/v2\/tags\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpi-europe.upv.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/cpi-europe.upv.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/cpi-europe.upv.es\/en\/wp-json\/wp\/v2\/posts?tags=110"},{"href":"https:\/\/cpi-europe.upv.es\/en\/wp-json\/wp\/v2\/mec-events?tags=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}